{"id":43,"count":3,"description":"","link":"https:\/\/blog.citrus-lime.com\/wch\/tag\/hoka\/","name":"Hoka","slug":"hoka","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.citrus-lime.com\/wch\/tag\/hoka\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/43\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch\\\/tag\\\/hoka\\\/#listItem\",\"name\":\"Hoka\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch\\\/tag\\\/hoka\\\/#listItem\",\"position\":2,\"name\":\"Hoka\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/43\\\/#collectionpage\",\"url\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/43\\\/\",\"name\":\"Hoka - Working Class Heroes Blog\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/43\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch\\\/#organization\",\"name\":\"Working Class Heroes Blog\",\"url\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch\\\/#website\",\"url\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch\\\/\",\"name\":\"Working Class Heroes Blog\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.citrus-lime.com\\\/wch\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Hoka - Working Class Heroes Blog","description":"","canonical_url":"https:\/\/blog.citrus-lime.com\/wch\/tag\/hoka\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/blog.citrus-lime.com\/wch\/wp-json\/wp\/v2\/tags\/43\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.citrus-lime.com\/wch#listItem","position":1,"name":"Home","item":"https:\/\/blog.citrus-lime.com\/wch","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.citrus-lime.com\/wch\/tag\/hoka\/#listItem","name":"Hoka"}},{"@type":"ListItem","@id":"https:\/\/blog.citrus-lime.com\/wch\/tag\/hoka\/#listItem","position":2,"name":"Hoka","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.citrus-lime.com\/wch#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/blog.citrus-lime.com\/wch\/wp-json\/wp\/v2\/tags\/43\/#collectionpage","url":"https:\/\/blog.citrus-lime.com\/wch\/wp-json\/wp\/v2\/tags\/43\/","name":"Hoka - Working Class Heroes Blog","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/blog.citrus-lime.com\/wch\/#website"},"breadcrumb":{"@id":"https:\/\/blog.citrus-lime.com\/wch\/wp-json\/wp\/v2\/tags\/43\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/blog.citrus-lime.com\/wch\/#organization","name":"Working Class Heroes Blog","url":"https:\/\/blog.citrus-lime.com\/wch\/"},{"@type":"WebSite","@id":"https:\/\/blog.citrus-lime.com\/wch\/#website","url":"https:\/\/blog.citrus-lime.com\/wch\/","name":"Working Class Heroes Blog","inLanguage":"en-GB","publisher":{"@id":"https:\/\/blog.citrus-lime.com\/wch\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.citrus-lime.com\/wch\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHoka\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.citrus-lime.com\/wch"},{"label":"Hoka","link":"https:\/\/blog.citrus-lime.com\/wch\/tag\/hoka\/"}],"_links":{"self":[{"href":"https:\/\/blog.citrus-lime.com\/wch\/wp-json\/wp\/v2\/tags\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.citrus-lime.com\/wch\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.citrus-lime.com\/wch\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.citrus-lime.com\/wch\/wp-json\/wp\/v2\/posts?tags=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}